{"id":1066,"date":"2020-03-30T10:32:27","date_gmt":"2020-03-30T10:32:27","guid":{"rendered":"https:\/\/pelicula.qodeinteractive.com\/?page_id=1066"},"modified":"2020-03-30T10:32:27","modified_gmt":"2020-03-30T10:32:27","slug":"about-us","status":"publish","type":"page","link":"http:\/\/noreset.ca\/index.php\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1066\" class=\"elementor elementor-1066\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f43f176 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"f43f176\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0765069\" data-id=\"0765069\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fdc83f elementor-widget elementor-widget-pelicula_core_icon_with_text\" data-id=\"0fdc83f\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-icon-with-text qodef-layout--top qodef--custom-icon qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"98\" height=\"98\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/custom-icon-img-1.png\" class=\"attachment-full size-full\" alt=\"c\" \/>\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h5 class=\"qodef-m-title\" >\n\t\t\t\t\t<span class=\"qodef-m-title-text\">our DIrectors<\/span>\n\t\t\t<\/h5>\n\t\t\t<p class=\"qodef-m-text\" >Lorem ipsum dolor sit amet, consec \ntur adipisicing elit, sed do.<\/p>\n\t<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d4f16c elementor-widget elementor-widget-spacer\" data-id=\"9d4f16c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d56497b\" data-id=\"d56497b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcdc9c0 elementor-widget elementor-widget-pelicula_core_icon_with_text\" data-id=\"dcdc9c0\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-icon-with-text qodef-layout--top qodef--custom-icon qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"98\" height=\"98\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/custom-icon-img-2.png\" class=\"attachment-full size-full\" alt=\"c\" \/>\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h5 class=\"qodef-m-title\" >\n\t\t\t\t\t<span class=\"qodef-m-title-text\">TV SHOWS<\/span>\n\t\t\t<\/h5>\n\t\t\t<p class=\"qodef-m-text\" >Lorem ipsum dolor sit amet, consec \ntur adipisicing elit, sed do.<\/p>\n\t<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4e1316 elementor-widget elementor-widget-spacer\" data-id=\"f4e1316\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3f7f386\" data-id=\"3f7f386\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fff8f7 elementor-widget elementor-widget-pelicula_core_icon_with_text\" data-id=\"5fff8f7\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-icon-with-text qodef-layout--top qodef--custom-icon qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"98\" height=\"98\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/custom-icon-img-3.png\" class=\"attachment-full size-full\" alt=\"c\" \/>\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h5 class=\"qodef-m-title\" >\n\t\t\t\t\t<span class=\"qodef-m-title-text\">FILM AWARDS<\/span>\n\t\t\t<\/h5>\n\t\t\t<p class=\"qodef-m-text\" >Lorem ipsum dolor sit amet, consec \ntur adipisicing elit, sed do.<\/p>\n\t<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5df4dcb elementor-widget elementor-widget-spacer\" data-id=\"5df4dcb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9c1ecbf\" data-id=\"9c1ecbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b62ffd elementor-widget elementor-widget-pelicula_core_icon_with_text\" data-id=\"2b62ffd\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-icon-with-text qodef-layout--top qodef--custom-icon qodef-alignment--center\">\n\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"98\" height=\"98\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/custom-icon-img-4.png\" class=\"attachment-full size-full\" alt=\"c\" \/>\t\t<\/div>\n\t<div class=\"qodef-m-content\">\n\t\t\t<h5 class=\"qodef-m-title\" >\n\t\t\t\t\t<span class=\"qodef-m-title-text\">FILM FESTIVALS<\/span>\n\t\t\t<\/h5>\n\t\t\t<p class=\"qodef-m-text\" >Lorem ipsum dolor sit amet, consec \ntur adipisicing elit, sed do.<\/p>\n\t<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dace9ff elementor-widget elementor-widget-spacer\" data-id=\"dace9ff\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d0cab1 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"7d0cab1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f9aa05\" data-id=\"2f9aa05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec5db30 elementor-widget elementor-widget-pelicula_core_horizontal_timeline\" data-id=\"ec5db30\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_horizontal_timeline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-horizontal-timeline  qodef-autoplay--enabled\" data-distance=\"60\">\n\t<div class=\"qodef-m-ht-nav\">\n\t\t<div class=\"qodef-m-ht-nav-wrapper\">\n\t\t\t<div class=\"qodef-m-ht-nav-inner\">\n\t\t\t\t<ol>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"#\" data-date=\"01\/01\/1980\">1980<span class=\"qodef-m-ht-nav-line-through\"><\/span><\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"#\" data-date=\"01\/01\/1987\">1987<span class=\"qodef-m-ht-nav-line-through\"><\/span><\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"#\" data-date=\"01\/01\/1995\">1995<span class=\"qodef-m-ht-nav-line-through\"><\/span><\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"#\" data-date=\"01\/01\/2004\">2004<span class=\"qodef-m-ht-nav-line-through\"><\/span><\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"#\" data-date=\"01\/01\/2006\">2006<span class=\"qodef-m-ht-nav-line-through\"><\/span><\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"#\" data-date=\"01\/01\/2018\">2018<span class=\"qodef-m-ht-nav-line-through\"><\/span><\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<a href=\"#\" data-date=\"01\/01\/2022\">2022<span class=\"qodef-m-ht-nav-line-through\"><\/span><\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\t\t\t\t<span class=\"qodef-m-ht-nav-filling-line\" aria-hidden=\"true\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<ul class=\"qodef-m-ht-nav-navigation\">\n\t\t\t<li><a href=\"#\" class=\"ion-md-arrow-dropleft qodef-prev qodef-inactive\"><\/a><\/li>\n\t\t\t<li><a href=\"#\" class=\"ion-md-arrow-dropright qodef-next\"><\/a><\/li>\n\t\t<\/ul>\n\t<\/div>\n\t\t\t<div class=\"qodef-m-ht-content\">\n\t\t\t<ol class=\"qodef-m-items\">\n\t\t\t\t\t\t\t\t\t<li class=\"qodef-m-item qodef-e\" data-date=\"01\/01\/1980\">\n\t\t\t\t\t\t<div class=\"qodef-e-hti-content-inner qodef-timeline-has-image\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-image\">\n\t\t\t                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-1.jpg\" class=\"qodef-m-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-1.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-1-300x169.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-1-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-value\">\n\t\t\t\t                \t\t\t                        <h3 class=\"qodef-e-title\">\n\t\t\t\t                        \u201cphantamogoria\u201d\t\t\t                        <\/h3>\n\t\t\t                    \n\t\t\t                    \t\t\t                        <p class=\"qodef-e-text\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation.<\/p>\n\t\t\t                    \n\t\t\t                    <a class=\"qodef-shortcode qodef-m qodef-e-button qodef-button qodef-layout--textual qodef-size--normal qodef-html--link\" href=\"https:\/\/pelicula.qodeinteractive.com\/portfolio-item\/what-lies-beyond\/\" target=\"_self\"  >\t<span class=\"qodef-m-text\">Learn More<\/span><\/a>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li class=\"qodef-m-item qodef-e\" data-date=\"01\/01\/1987\">\n\t\t\t\t\t\t<div class=\"qodef-e-hti-content-inner qodef-timeline-has-image\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-image\">\n\t\t\t                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-2.jpg\" class=\"qodef-m-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-2.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-2-300x169.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-2-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-value\">\n\t\t\t\t                \t\t\t                        <h3 class=\"qodef-e-title\">\n\t\t\t\t                        \u201coutcast\u201d\t\t\t                        <\/h3>\n\t\t\t                    \n\t\t\t                    \t\t\t                        <p class=\"qodef-e-text\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation.<\/p>\n\t\t\t                    \n\t\t\t                    <a class=\"qodef-shortcode qodef-m qodef-e-button qodef-button qodef-layout--textual qodef-size--normal qodef-html--link\" href=\"https:\/\/pelicula.qodeinteractive.com\/portfolio-item\/the-eternal-void\/\" target=\"_self\"  >\t<span class=\"qodef-m-text\">Learn More<\/span><\/a>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li class=\"qodef-m-item qodef-e\" data-date=\"01\/01\/1995\">\n\t\t\t\t\t\t<div class=\"qodef-e-hti-content-inner qodef-timeline-has-image\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-image\">\n\t\t\t                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-3.jpg\" class=\"qodef-m-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-3.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-3-300x169.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-3-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-value\">\n\t\t\t\t                \t\t\t                        <h3 class=\"qodef-e-title\">\n\t\t\t\t                        &quot;Rework&quot;\t\t\t                        <\/h3>\n\t\t\t                    \n\t\t\t                    \t\t\t                        <p class=\"qodef-e-text\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation.<\/p>\n\t\t\t                    \n\t\t\t                    <a class=\"qodef-shortcode qodef-m qodef-e-button qodef-button qodef-layout--textual qodef-size--normal qodef-html--link\" href=\"https:\/\/pelicula.qodeinteractive.com\/portfolio-item\/hueco-mundo\/\" target=\"_self\"  >\t<span class=\"qodef-m-text\">Learn More<\/span><\/a>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li class=\"qodef-m-item qodef-e\" data-date=\"01\/01\/2004\">\n\t\t\t\t\t\t<div class=\"qodef-e-hti-content-inner qodef-timeline-has-image\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-image\">\n\t\t\t                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-4.jpg\" class=\"qodef-m-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-4.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-4-300x169.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-4-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-value\">\n\t\t\t\t                \t\t\t                        <h3 class=\"qodef-e-title\">\n\t\t\t\t                        &quot;Dark Tunnel&quot;\t\t\t                        <\/h3>\n\t\t\t                    \n\t\t\t                    \t\t\t                        <p class=\"qodef-e-text\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation.<\/p>\n\t\t\t                    \n\t\t\t                    <a class=\"qodef-shortcode qodef-m qodef-e-button qodef-button qodef-layout--textual qodef-size--normal qodef-html--link\" href=\"https:\/\/pelicula.qodeinteractive.com\/portfolio-item\/see-the-light\/\" target=\"_self\"  >\t<span class=\"qodef-m-text\">Learn More<\/span><\/a>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li class=\"qodef-m-item qodef-e\" data-date=\"01\/01\/2006\">\n\t\t\t\t\t\t<div class=\"qodef-e-hti-content-inner qodef-timeline-has-image\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-image\">\n\t\t\t                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-5.jpg\" class=\"qodef-m-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-5.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-5-300x169.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-5-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-value\">\n\t\t\t\t                \t\t\t                        <h3 class=\"qodef-e-title\">\n\t\t\t\t                        &quot;Proactive&quot;\t\t\t                        <\/h3>\n\t\t\t                    \n\t\t\t                    \t\t\t                        <p class=\"qodef-e-text\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation.<\/p>\n\t\t\t                    \n\t\t\t                    <a class=\"qodef-shortcode qodef-m qodef-e-button qodef-button qodef-layout--textual qodef-size--normal qodef-html--link\" href=\"https:\/\/pelicula.qodeinteractive.com\/portfolio-item\/finding-art\/\" target=\"_self\"  >\t<span class=\"qodef-m-text\">Learn More<\/span><\/a>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li class=\"qodef-m-item qodef-e\" data-date=\"01\/01\/2018\">\n\t\t\t\t\t\t<div class=\"qodef-e-hti-content-inner qodef-timeline-has-image\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-image\">\n\t\t\t                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-6.jpg\" class=\"qodef-m-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-6.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-6-300x169.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-6-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-value\">\n\t\t\t\t                \t\t\t                        <h3 class=\"qodef-e-title\">\n\t\t\t\t                        &quot;The Return&quot;\t\t\t                        <\/h3>\n\t\t\t                    \n\t\t\t                    \t\t\t                        <p class=\"qodef-e-text\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation.<\/p>\n\t\t\t                    \n\t\t\t                    <a class=\"qodef-shortcode qodef-m qodef-e-button qodef-button qodef-layout--textual qodef-size--normal qodef-html--link\" href=\"https:\/\/pelicula.qodeinteractive.com\/portfolio-item\/our-future\/\" target=\"_self\"  >\t<span class=\"qodef-m-text\">Learn More<\/span><\/a>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li class=\"qodef-m-item qodef-e\" data-date=\"01\/01\/2022\">\n\t\t\t\t\t\t<div class=\"qodef-e-hti-content-inner qodef-timeline-has-image\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-image\">\n\t\t\t                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-7.jpg\" class=\"qodef-m-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-7.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-7-300x169.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/04\/timeline-img-7-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"qodef-e-hti-content-value\">\n\t\t\t\t                \t\t\t                        <h3 class=\"qodef-e-title\">\n\t\t\t\t                        &quot;Stolen Wind&quot;\t\t\t                        <\/h3>\n\t\t\t                    \n\t\t\t                    \t\t\t                        <p class=\"qodef-e-text\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation.<\/p>\n\t\t\t                    \n\t\t\t                    <a class=\"qodef-shortcode qodef-m qodef-e-button qodef-button qodef-layout--textual qodef-size--normal qodef-html--link\" href=\"https:\/\/pelicula.qodeinteractive.com\/portfolio-item\/fresh-start\/\" target=\"_self\"  >\t<span class=\"qodef-m-text\">Learn More<\/span><\/a>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ol>\n\t\t<\/div>\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-251e527 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"251e527\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-088c5b2\" data-id=\"088c5b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-791914a elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"791914a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a663eda\" data-id=\"a663eda\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34ebfe6 elementor-widget elementor-widget-pelicula_core_section_title\" data-id=\"34ebfe6\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--right \" data-holder-options=\"{&quot;line-breaks&quot;:&quot;&quot;}\">\n\t\t<h6 class=\"qodef-m-tagline\" style=\"color: #A6A6A6\">\n\t\tour experience\t<\/h6>\n\t    \t<h3 class=\"qodef-m-title\" >\n\t\t\t8 Years of Innovation\t<\/h3>\n    \t\t<p class=\"qodef-m-text\" >Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim<\/p>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b3d69 elementor-widget elementor-widget-spacer\" data-id=\"77b3d69\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb1ac55 elementor-widget__width-auto elementor-widget elementor-widget-pelicula_core_button\" data-id=\"fb1ac55\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a class=\"qodef-shortcode qodef-m  qodef-button qodef-layout--filled  qodef-html--link\" href=\"https:\/\/pelicula.qodeinteractive.com\/welcome-to-sky-valley\/\" target=\"_self\" data-background-color=\"#FFFFFF\" style=\"color: #111111;background-color: #FFFFFF;border-color: #FFFFFF\">\n\t<span class=\"qodef-m-text\">learn more<\/span>\n<\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-edc2de6 qodef-in-focus\" data-id=\"edc2de6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d18efb5 elementor-widget elementor-widget-spacer\" data-id=\"d18efb5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2f9412 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"e2f9412\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8ff84c\" data-id=\"f8ff84c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a10de4 elementor-widget elementor-widget-pelicula_core_testimonials_list\" data-id=\"3a10de4\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_testimonials_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-testimonials-list qodef-separator--enabled  qodef-grid qodef-swiper-container   qodef-gutter--medium qodef-col-num--2 qodef-item-layout--info-below qodef-responsive--predefined\" data-options=\"{&quot;slidesPerView&quot;:&quot;2&quot;,&quot;spaceBetween&quot;:20,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;&quot;,&quot;slideAnimation&quot;:&quot;&quot;,&quot;unique&quot;:4576,&quot;outsideNavigation&quot;:&quot;yes&quot;}\">\n\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"qodef-e qodef-testimonials-holder swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-content\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t\t&quot;An Intense Experience&quot;\t<\/h4>\n\t\t\t\t<p itemprop=\"description\" class=\"qodef-e-text\">\n\t\t&quot;Proin gravida nibh vel velit auctor aquet. Aenean sollicitudin, lorem quis bibe\u201d auctor, nisi elit consequat ipsum, nec sagittis sem nibh id elit. Duis sed odio sit amet nibh vulputate cursus. Donec quam felis, ultricies&quot;\t<\/p>\n\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/testimonial-image-2-53x53.jpg\" alt=\"a\" width=\"53\" height=\"53\" data-ratio=\"1\" \/>\t<\/div>\n\t\t\t\t<div class=\"qodef-e-author\">\n\t<h6 class=\"qodef-e-author-name\">\n\t\tRobert Shuman\t<\/h6>\n\t<span class=\"qodef-e-author-job\">\n\t\tThe Guardian\t<\/span>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"qodef-e qodef-testimonials-holder swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-content\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t\t&quot;Visualy Over-powering\t<\/h4>\n\t\t\t\t<p itemprop=\"description\" class=\"qodef-e-text\">\n\t\t&quot;Proin gravida nibh vel velit auctor aquet. Aenean sollicitudin, lorem quis bibe\u201d auctor, nisi elit consequat ipsum, nec sagittis sem nibh id elit. Duis sed odio sit amet nibh vulputate cursus. Donec quam felis, ultricies&quot;\t<\/p>\n\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/testimonial-image-1-53x53.jpg\" alt=\"a\" width=\"53\" height=\"53\" data-ratio=\"1\" \/>\t<\/div>\n\t\t\t\t<div class=\"qodef-e-author\">\n\t<h6 class=\"qodef-e-author-name\">\n\t\tAmanda Gilles\t<\/h6>\n\t<span class=\"qodef-e-author-job\">\n\t\tTimes Magazine\t<\/span>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"qodef-e qodef-testimonials-holder swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-content\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title entry-title\" >\n\t\t&quot;Amazing Soundtrack&quot;\t<\/h4>\n\t\t\t\t<p itemprop=\"description\" class=\"qodef-e-text\">\n\t\t&quot;Proin gravida nibh vel velit auctor aquet. Aenean sollicitudin, lorem quis bibe\u201d auctor, nisi elit consequat ipsum, nec sagittis sem nibh id elit. Duis sed odio sit amet nibh vulputate cursus. Donec quam felis, ultricies&quot;\t<\/p>\n\t\t\t<div class=\"qodef-e-info\">\n\t\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/user-2-53x53.jpg\" alt=\"a\" width=\"53\" height=\"53\" data-ratio=\"1\" \/>\t<\/div>\n\t\t\t\t<div class=\"qodef-e-author\">\n\t<h6 class=\"qodef-e-author-name\">\n\t\tDonna Louis\t<\/h6>\n\t<span class=\"qodef-e-author-job\">\n\t\tVariety\t<\/span>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t<\/div>\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6056d87 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"6056d87\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ed05ca\" data-id=\"6ed05ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd95958 elementor-widget elementor-widget-pelicula_core_team_list\" data-id=\"cd95958\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_team_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m qodef-in-focus qodef-team-list  qodef-item-layout--info-below qodef-grid qodef-layout--columns   qodef-gutter--normal qodef-col-num--3 qodef-item-layout--info-below qodef--no-bottom-space qodef-pagination--off qodef-responsive--predefined\" data-options=\"{&quot;plugin&quot;:&quot;pelicula_core&quot;,&quot;module&quot;:&quot;post-types\\\/team\\\/shortcodes&quot;,&quot;shortcode&quot;:&quot;team-list&quot;,&quot;post_type&quot;:&quot;team&quot;,&quot;next_page&quot;:&quot;2&quot;,&quot;max_pages_num&quot;:1,&quot;custom_class&quot;:&quot;qodef-in-focus&quot;,&quot;behavior&quot;:&quot;columns&quot;,&quot;images_proportion&quot;:&quot;full&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_responsive&quot;:&quot;predefined&quot;,&quot;space&quot;:&quot;normal&quot;,&quot;posts_per_page&quot;:&quot;3&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;ASC&quot;,&quot;additional_params&quot;:&quot;tax&quot;,&quot;tax&quot;:&quot;team-category&quot;,&quot;tax_slug&quot;:&quot;about-us&quot;,&quot;layout&quot;:&quot;info-below&quot;,&quot;title_tag&quot;:&quot;h4&quot;,&quot;pagination_type&quot;:&quot;no-pagination&quot;,&quot;object_class_name&quot;:&quot;PeliculaCoreTeamListShortcode&quot;,&quot;taxonomy_filter&quot;:&quot;team-category&quot;,&quot;additional_query_args&quot;:{&quot;tax_query&quot;:[{&quot;taxonomy&quot;:&quot;team-category&quot;,&quot;field&quot;:&quot;slug&quot;,&quot;terms&quot;:&quot;about-us&quot;}]},&quot;item_classes&quot;:&quot;qodef-e qodef-e-holder-main qodef-grid-item&quot;,&quot;space_value&quot;:15}\">\n\t\t<div class=\"qodef-grid-inner clear\">\n\t\t<div class=\"qodef-e qodef-e-holder-main qodef-grid-item qodef-has-post-media post-1088 team type-team status-publish has-post-thumbnail hentry team-category-about-us\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-1.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-1-300x300.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-1-150x150.jpg 150w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-1-768x768.jpg 768w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-1-650x650.jpg 650w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content qodef-e-content-main\" >\n\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title qodef-e-title-main entry-title\" >\n\t\t\tAlex Gray\t<\/h4>\t\t\t\t<p class=\"qodef-e-role\">\n\t\tMain Director\t<\/p>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"qodef-e qodef-e-holder-main qodef-grid-item qodef-has-post-media post-1089 team type-team status-publish has-post-thumbnail hentry team-category-about-us\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-2.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-2-300x300.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-2-150x150.jpg 150w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-2-768x768.jpg 768w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-2-650x650.jpg 650w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content qodef-e-content-main\" >\n\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title qodef-e-title-main entry-title\" >\n\t\t\tEve Longsteen\t<\/h4>\t\t\t\t<p class=\"qodef-e-role\">\n\t\tMain Writer\t<\/p>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"qodef-e qodef-e-holder-main qodef-grid-item qodef-has-post-media post-1092 team type-team status-publish has-post-thumbnail hentry team-category-about-us\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-image\">\n\t\t\t\t<div class=\"qodef-e-media-image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-3.jpg 800w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-3-300x300.jpg 300w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-3-150x150.jpg 150w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-3-768x768.jpg 768w, http:\/\/noreset.ca\/wp-content\/uploads\/2020\/03\/p1-team-img-3-650x650.jpg 650w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"qodef-e-content qodef-e-content-main\" >\n\t\t\t<h4 itemprop=\"name\" class=\"qodef-e-title qodef-e-title-main entry-title\" >\n\t\t\tEsteban Riccasso\t<\/h4>\t\t\t\t<p class=\"qodef-e-role\">\n\t\tMain Producer\t<\/p>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\t<\/div>\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2a815b elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"e2a815b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-df465e9\" data-id=\"df465e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f78368 elementor-widget elementor-widget-pelicula_core_section_title\" data-id=\"7f78368\" data-element_type=\"widget\" data-widget_type=\"pelicula_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--right \" data-holder-options=\"{&quot;line-breaks&quot;:&quot;&quot;}\">\n\t\t<h6 class=\"qodef-m-tagline\" style=\"color: #6D6D6D\">\n\t\tCollaborate\t<\/h6>\n\t    \t<h2 class=\"qodef-m-title\" >\n\t\t\tWant To Work With US? Leave Us a Message!\t<\/h2>\n    \t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cc5799 elementor-widget elementor-widget-spacer\" data-id=\"6cc5799\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8707d5 e-grid-align-right elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"b8707d5\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)));height:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#69727d;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#69727d}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-08490c1\" href=\"https:\/\/www.youtube.com\/QodeInteractiveVideos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-11e2500\" href=\"https:\/\/www.instagram.com\/qodeinteractive\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8a26405\" href=\"https:\/\/twitter.com\/QodeInteractive\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-5cd72d7\" href=\"https:\/\/www.facebook.com\/QodeInteractive\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-003ab5a elementor-widget elementor-widget-spacer\" data-id=\"003ab5a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b99ed40\" data-id=\"b99ed40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ee469a elementor-widget elementor-widget-wp-widget-pelicula_core_contact_form_7\" data-id=\"6ee469a\" data-element_type=\"widget\" data-widget_type=\"wp-widget-pelicula_core_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"qodef-contact-form-7\">\n\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f594-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/1066#wpcf7-f594-o1\" method=\"post\" class=\"wpcf7-form init demo\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"594\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.7\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f594-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Type your message\" name=\"your-message\"><\/textarea><\/span>\n\n<div class=\"qodef-grid qodef-layout--columns qodef-col-num--2 qodef-responsive--predefined\">\n    <div class=\"qodef-grid-inner\">\n        <div class=\"qodef-grid-item\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/div>\n        <div class=\"qodef-grid-item\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/div><\/div><\/div>\n\n<button class=\"wpcf7-form-control wpcf7-submit qodef-size--full-width qodef-button qodef-size--normal qodef-type--filled qodef-m\" type=\"submit\"><span class=\"qodef-m-text\">Send<\/span><\/button><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-273a8de elementor-widget elementor-widget-spacer\" data-id=\"273a8de\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>our DIrectors Lorem ipsum dolor sit amet, consec tur adipisicing elit, sed do. TV SHOWS Lorem ipsum dolor sit amet, consec tur adipisicing elit, sed do. FILM AWARDS Lorem ipsum dolor sit amet, consec tur adipisicing elit, sed do. FILM FESTIVALS Lorem ipsum dolor sit amet, consec tur adipisicing elit, sed do. 1980 1987 1995 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-1066","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/noreset.ca\/index.php\/wp-json\/wp\/v2\/pages\/1066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/noreset.ca\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/noreset.ca\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/noreset.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/noreset.ca\/index.php\/wp-json\/wp\/v2\/comments?post=1066"}],"version-history":[{"count":0,"href":"http:\/\/noreset.ca\/index.php\/wp-json\/wp\/v2\/pages\/1066\/revisions"}],"wp:attachment":[{"href":"http:\/\/noreset.ca\/index.php\/wp-json\/wp\/v2\/media?parent=1066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}